{"id":4,"count":16,"description":"","link":"https:\/\/peterlindberg.com\/blog\/category\/fashion\/","name":"Fashion","slug":"fashion","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}