{"id":149,"count":1,"description":"","link":"https:\/\/peterlindberg.com\/blog\/tag\/tanja-malo\/","name":"tanja malo","slug":"tanja-malo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/tags\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/posts?tags=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}