{"id":168,"count":1,"description":"","link":"https:\/\/peterlindberg.com\/blog\/tag\/50s\/","name":"50's","slug":"50s","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/tags\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/peterlindberg.com\/blog\/wp-json\/wp\/v2\/posts?tags=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}